{"id":3033,"date":"2023-10-17T11:47:09","date_gmt":"2023-10-17T09:47:09","guid":{"rendered":"https:\/\/www.wg-avocats.ch\/competences\/streitigkeiten-im-handelsrecht\/"},"modified":"2025-02-26T12:13:04","modified_gmt":"2025-02-26T11:13:04","slug":"streitigkeiten-im-handelsrecht","status":"publish","type":"competences","link":"http:\/\/www.wg-avocats.ch\/de\/kompetenzen\/expertise-handelsrecht\/streitigkeiten-im-handelsrecht\/","title":{"rendered":"Unternehmensumstrukturierung"},"content":{"rendered":"","protected":false},"parent":3061,"menu_order":0,"template":"","format":"standard","class_list":["post-3033","competences","type-competences","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Streitigkeiten im Handelsrecht - Anwaltskanzlei in Lausanne<\/title>\n<meta name=\"description\" content=\"Wilhelm Gilli\u00e9ron Rechtsanw\u00e4lte verf\u00fcgt \u00fcber eine umfassende Expertise im Bereich der Unternehmensrestrukturierung. Wir beraten Sie in Lausanne und in der Schweiz.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.wg-avocats.ch\/de\/kompetenzen\/expertise-handelsrecht\/streitigkeiten-im-handelsrecht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Streitigkeiten im Handelsrecht - Anwaltskanzlei in Lausanne\" \/>\n<meta property=\"og:description\" content=\"Wilhelm Gilli\u00e9ron Rechtsanw\u00e4lte verf\u00fcgt \u00fcber eine umfassende Expertise im Bereich der Unternehmensrestrukturierung. Wir beraten Sie in Lausanne und in der Schweiz.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.wg-avocats.ch\/de\/kompetenzen\/expertise-handelsrecht\/streitigkeiten-im-handelsrecht\/\" \/>\n<meta property=\"og:site_name\" content=\"Wilhelm Avocats\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-26T11:13:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.wg-avocats.ch\\\/de\\\/kompetenzen\\\/expertise-handelsrecht\\\/streitigkeiten-im-handelsrecht\\\/\",\"url\":\"http:\\\/\\\/www.wg-avocats.ch\\\/de\\\/kompetenzen\\\/expertise-handelsrecht\\\/streitigkeiten-im-handelsrecht\\\/\",\"name\":\"Streitigkeiten im Handelsrecht - Anwaltskanzlei in Lausanne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.wg-avocats.ch\\\/de\\\/#website\"},\"datePublished\":\"2023-10-17T09:47:09+00:00\",\"dateModified\":\"2025-02-26T11:13:04+00:00\",\"description\":\"Wilhelm Gilli\u00e9ron Rechtsanw\u00e4lte verf\u00fcgt \u00fcber eine umfassende Expertise im Bereich der Unternehmensrestrukturierung. Wir beraten Sie in Lausanne und in der Schweiz.\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.wg-avocats.ch\\\/de\\\/kompetenzen\\\/expertise-handelsrecht\\\/streitigkeiten-im-handelsrecht\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.wg-avocats.ch\\\/de\\\/kompetenzen\\\/expertise-handelsrecht\\\/streitigkeiten-im-handelsrecht\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.wg-avocats.ch\\\/de\\\/kompetenzen\\\/expertise-handelsrecht\\\/streitigkeiten-im-handelsrecht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.wg-avocats.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comp\u00e9tences\",\"item\":\"https:\\\/\\\/www.wg-avocats.ch\\\/competences\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Expertise Handelsrecht\",\"item\":\"http:\\\/\\\/www.wg-avocats.ch\\\/de\\\/kompetenzen\\\/expertise-handelsrecht\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Unternehmensumstrukturierung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.wg-avocats.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.wg-avocats.ch\\\/de\\\/\",\"name\":\"Wilhelm Avocats\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.wg-avocats.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.wg-avocats.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.wg-avocats.ch\\\/de\\\/#organization\",\"name\":\"Wilhelm Avocats\",\"url\":\"https:\\\/\\\/www.wg-avocats.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.wg-avocats.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.wg-avocats.ch\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/wilhelm-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.wg-avocats.ch\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/wilhelm-logo.png\",\"width\":809,\"height\":144,\"caption\":\"Wilhelm Avocats\"},\"image\":{\"@id\":\"https:\\\/\\\/www.wg-avocats.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/9387689\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Streitigkeiten im Handelsrecht - Anwaltskanzlei in Lausanne","description":"Wilhelm Gilli\u00e9ron Rechtsanw\u00e4lte verf\u00fcgt \u00fcber eine umfassende Expertise im Bereich der Unternehmensrestrukturierung. Wir beraten Sie in Lausanne und in der Schweiz.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.wg-avocats.ch\/de\/kompetenzen\/expertise-handelsrecht\/streitigkeiten-im-handelsrecht\/","og_locale":"de_DE","og_type":"article","og_title":"Streitigkeiten im Handelsrecht - Anwaltskanzlei in Lausanne","og_description":"Wilhelm Gilli\u00e9ron Rechtsanw\u00e4lte verf\u00fcgt \u00fcber eine umfassende Expertise im Bereich der Unternehmensrestrukturierung. Wir beraten Sie in Lausanne und in der Schweiz.","og_url":"http:\/\/www.wg-avocats.ch\/de\/kompetenzen\/expertise-handelsrecht\/streitigkeiten-im-handelsrecht\/","og_site_name":"Wilhelm Avocats","article_modified_time":"2025-02-26T11:13:04+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.wg-avocats.ch\/de\/kompetenzen\/expertise-handelsrecht\/streitigkeiten-im-handelsrecht\/","url":"http:\/\/www.wg-avocats.ch\/de\/kompetenzen\/expertise-handelsrecht\/streitigkeiten-im-handelsrecht\/","name":"Streitigkeiten im Handelsrecht - Anwaltskanzlei in Lausanne","isPartOf":{"@id":"https:\/\/www.wg-avocats.ch\/de\/#website"},"datePublished":"2023-10-17T09:47:09+00:00","dateModified":"2025-02-26T11:13:04+00:00","description":"Wilhelm Gilli\u00e9ron Rechtsanw\u00e4lte verf\u00fcgt \u00fcber eine umfassende Expertise im Bereich der Unternehmensrestrukturierung. Wir beraten Sie in Lausanne und in der Schweiz.","breadcrumb":{"@id":"http:\/\/www.wg-avocats.ch\/de\/kompetenzen\/expertise-handelsrecht\/streitigkeiten-im-handelsrecht\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.wg-avocats.ch\/de\/kompetenzen\/expertise-handelsrecht\/streitigkeiten-im-handelsrecht\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.wg-avocats.ch\/de\/kompetenzen\/expertise-handelsrecht\/streitigkeiten-im-handelsrecht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.wg-avocats.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Comp\u00e9tences","item":"https:\/\/www.wg-avocats.ch\/competences\/"},{"@type":"ListItem","position":3,"name":"Expertise Handelsrecht","item":"http:\/\/www.wg-avocats.ch\/de\/kompetenzen\/expertise-handelsrecht\/"},{"@type":"ListItem","position":4,"name":"Unternehmensumstrukturierung"}]},{"@type":"WebSite","@id":"https:\/\/www.wg-avocats.ch\/de\/#website","url":"https:\/\/www.wg-avocats.ch\/de\/","name":"Wilhelm Avocats","description":"","publisher":{"@id":"https:\/\/www.wg-avocats.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.wg-avocats.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.wg-avocats.ch\/de\/#organization","name":"Wilhelm Avocats","url":"https:\/\/www.wg-avocats.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.wg-avocats.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.wg-avocats.ch\/wp-content\/uploads\/2023\/09\/wilhelm-logo.png","contentUrl":"https:\/\/www.wg-avocats.ch\/wp-content\/uploads\/2023\/09\/wilhelm-logo.png","width":809,"height":144,"caption":"Wilhelm Avocats"},"image":{"@id":"https:\/\/www.wg-avocats.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/9387689"]}]}},"_links":{"self":[{"href":"https:\/\/www.wg-avocats.ch\/de\/wp-json\/wp\/v2\/competences\/3033","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wg-avocats.ch\/de\/wp-json\/wp\/v2\/competences"}],"about":[{"href":"https:\/\/www.wg-avocats.ch\/de\/wp-json\/wp\/v2\/types\/competences"}],"up":[{"embeddable":true,"href":"https:\/\/www.wg-avocats.ch\/de\/wp-json\/wp\/v2\/competences\/3061"}],"wp:attachment":[{"href":"https:\/\/www.wg-avocats.ch\/de\/wp-json\/wp\/v2\/media?parent=3033"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}